{"id":13953,"date":"2017-11-25T08:04:10","date_gmt":"2017-11-25T08:04:10","guid":{"rendered":"http:\/\/launcestonthen.co.uk\/?page_id=13953"},"modified":"2017-11-25T08:04:10","modified_gmt":"2017-11-25T08:04:10","slug":"tresmeer-marriage-register-1813-1837","status":"publish","type":"page","link":"https:\/\/launcestonthen.co.uk\/index.php\/the-parishes\/tresmeer\/tresmeer-marriage-register-1813-1837\/","title":{"rendered":"Tresmeer Marriage Register 1813-1837"},"content":{"rendered":"<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n\n<table id=\"tablepress-2\" class=\"tablepress tablepress-id-2\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">GROOOM<\/th><th class=\"column-2\">BRIDE<\/th><th class=\"column-3\">DATE<\/th><th class=\"column-4\">WITNESS<\/th><th class=\"column-5\">WITNESS<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">Nicholas VEAL of Tremain<\/td><td class=\"column-2\">Joanna HORREL otp<\/td><td class=\"column-3\">4 Apr 1815<\/td><td class=\"column-4\">Henry Marshall<\/td><td class=\"column-5\">John Wroath<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">Abel HICKS of Warbstow<\/td><td class=\"column-2\">Catherine PHYSICK otp<\/td><td class=\"column-3\">15 Feb 1816<\/td><td class=\"column-4\">William Parsons<\/td><td class=\"column-5\">George Uglow<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">Robert OLIVER of Bridestow<\/td><td class=\"column-2\">Catherine UGLOW otp<\/td><td class=\"column-3\">1 Jan 1817<\/td><td class=\"column-4\">Henry Williams <\/td><td class=\"column-5\">Henry Marshall<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">John BATE of Warbstow<\/td><td class=\"column-2\">Margaret MARSHALL otp<\/td><td class=\"column-3\">18 Nov 1817<\/td><td class=\"column-4\">Uriah Matthew<\/td><td class=\"column-5\">Henry Marshall<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">Walter PEARSE of Egloskerry<\/td><td class=\"column-2\">Ann HORREL otp<\/td><td class=\"column-3\">3 Feb 1820<\/td><td class=\"column-4\">Uriah Matthew<\/td><td class=\"column-5\">Philip Sandercock<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">Thomas BATE of Egloskerry<\/td><td class=\"column-2\">Mary JOHNS otp<\/td><td class=\"column-3\">13 Apr 1820<\/td><td class=\"column-4\">John Johns<\/td><td class=\"column-5\">Walter Bate<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">George SCAWN of St. Clether<\/td><td class=\"column-2\">Grace GIDDY otp<\/td><td class=\"column-3\">3 Apr 1821<\/td><td class=\"column-4\">Thomas Giddy<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">Thomas FRY otp<\/td><td class=\"column-2\">Elizabeth MATHEW otp<\/td><td class=\"column-3\">20 Mar 1823<\/td><td class=\"column-4\">Uriah Matthew<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">Matthew STEPHENS bachelor otp<\/td><td class=\"column-2\">Elizabeth KETT spinster otp<\/td><td class=\"column-3\">14 Mar 1824<\/td><td class=\"column-4\">William Ferrett<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">Peter HODGE of Warbstow<\/td><td class=\"column-2\">Charity WISE otp<\/td><td class=\"column-3\">20 June 1824<\/td><td class=\"column-4\">Thomas Phear<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">Joseph ROWE otp<\/td><td class=\"column-2\">Phillippa FRENCH otp<\/td><td class=\"column-3\">16 Aug 1825<\/td><td class=\"column-4\">Roger Marshall<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">William JEWELL otp<\/td><td class=\"column-2\">Alice FRENCH of Tremain<\/td><td class=\"column-3\">27 Mar 1828<\/td><td class=\"column-4\">John Stadon<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">William TURNER otp<\/td><td class=\"column-2\">Frances TREASE (Traise) otp<\/td><td class=\"column-3\">9 APR 1828<\/td><td class=\"column-4\">Uriah Matthew<\/td><td class=\"column-5\">Thomas Traise<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">John Chudley otp<\/td><td class=\"column-2\">Elizabeth KINVOR otp<\/td><td class=\"column-3\">17 Apr 1828<\/td><td class=\"column-4\">Uriah Matthew<\/td><td class=\"column-5\">Samuel Gilbert<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">Henry DOWN otp<\/td><td class=\"column-2\">Elizabeth JOHNS otp<\/td><td class=\"column-3\">30 Dec 1828<\/td><td class=\"column-4\">Thomas Bevin<\/td><td class=\"column-5\">Henry Johns<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">William SMALE bachelor of Egloskerry<\/td><td class=\"column-2\">Mary WILCOCKS spinster otp<\/td><td class=\"column-3\">9 Dec 1830<\/td><td class=\"column-4\">P. Ebbott<\/td><td class=\"column-5\">John Grylls<\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">Thomas TREASE bachelor otp<\/td><td class=\"column-2\">Mary PROUT spinster of Egloskerry<\/td><td class=\"column-3\">23 July 1831<\/td><td class=\"column-4\">Uriah Matthew<\/td><td class=\"column-5\">John Bate<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">Richard BONE bachelor Egloskerry<\/td><td class=\"column-2\">Harriot JOHNS spinster otp<\/td><td class=\"column-3\">27 ? 1831<\/td><td class=\"column-4\">John Johns<\/td><td class=\"column-5\">Henry Johns<\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">James GUEST bachelor &amp; sojourner in tp<\/td><td class=\"column-2\">Elizabeth FERRETT spinster otp<\/td><td class=\"column-3\">27 Mar 1834<\/td><td class=\"column-4\">John Bate<\/td><td class=\"column-5\">Uriah Matthew<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">William GRIGG bachelor of Duloe<\/td><td class=\"column-2\"> Ann PARSONS widow otp<\/td><td class=\"column-3\">1 Dec 1835<\/td><td class=\"column-4\">George Frayn<\/td><td class=\"column-5\">James Ching<\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">John PAYNTER (Painter) widower otp<\/td><td class=\"column-2\">Mary BOND widow otp<\/td><td class=\"column-3\">29 Dec 1835<\/td><td class=\"column-4\">William Smale <\/td><td class=\"column-5\">Ann <\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">John SMITH bachelor of Jacobstow<\/td><td class=\"column-2\">Elizabeth WICKETT spinster otp<\/td><td class=\"column-3\">16 Mar 1837<\/td><td class=\"column-4\">James Perkin<\/td><td class=\"column-5\">William Smale<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-2 from cache -->\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Visits: 293<\/p><!--themify_builder_content-->\n<div id=\"themify_builder_content-13953\" data-postid=\"13953\" class=\"themify_builder_content themify_builder_content-13953 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p>. &nbsp; &nbsp; &nbsp; Visits: 293<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4188,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-13953","page","type-page","status-publish","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/13953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/comments?post=13953"}],"version-history":[{"count":3,"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/13953\/revisions"}],"predecessor-version":[{"id":13962,"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/13953\/revisions\/13962"}],"up":[{"embeddable":true,"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/4188"}],"wp:attachment":[{"href":"https:\/\/launcestonthen.co.uk\/index.php\/wp-json\/wp\/v2\/media?parent=13953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}